{"id":2331,"date":"2024-03-31T00:26:22","date_gmt":"2024-03-31T07:26:22","guid":{"rendered":"https:\/\/pocencoffee.com\/?post_type=product&#038;p=2331"},"modified":"2024-03-31T00:26:22","modified_gmt":"2024-03-31T07:26:22","slug":"herramientas-para-baristas-mazos-de-cafe-calibrados","status":"publish","type":"product","link":"https:\/\/pocencoffee.com\/es\/product\/barista-tools-caribrated-coffee-tampers\/","title":{"rendered":"Herramientas para baristas: prensadores de caf\u00e9 calibrados"},"content":{"rendered":"<p><strong>Herramientas para baristas: prensadores de caf\u00e9 calibrados<\/strong><\/p>\n<p>Material: base de caf\u00e9 de acero inoxidable macizo, mango de aluminio.<\/p>\n<p>Tama\u00f1o: 51 mm, 53 mm, 58 mm<\/p>\n<p>Opciones de personalizaci\u00f3n: color, logotipo, embalaje.<\/p>\n<p>Base: plana, roscada y personalizable.<\/p>","protected":false},"excerpt":{"rendered":"<p>P\u00f3ngase en contacto con nosotros para personalizar sus pisones de caf\u00e9 calibrados.<\/p>","protected":false},"featured_media":2332,"template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":["post-2331","product","type-product","status-publish","has-post-thumbnail","product_cat-coffee-tamperscoffee-coffee-leveler","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product\/2331\/revisions"}],"predecessor-version":[{"id":2338,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product\/2331\/revisions\/2338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/media\/2332"}],"wp:attachment":[{"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product_brand?post=2331"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product_cat?post=2331"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pocencoffee.com\/es\/wp-json\/wp\/v2\/product_tag?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}