{"id":2528,"date":"2024-04-12T06:56:45","date_gmt":"2024-04-12T13:56:45","guid":{"rendered":"https:\/\/pocencoffee.com\/?post_type=product&#038;p=2528"},"modified":"2024-04-12T07:04:18","modified_gmt":"2024-04-12T14:04:18","slug":"tamponi-di-legno-allingrosso-per-il-caffe-a-scatto","status":"publish","type":"product","link":"https:\/\/pocencoffee.com\/it\/product\/tamponi-di-legno-allingrosso-per-il-caffe-a-scatto\/","title":{"rendered":"Tamponi per caff\u00e8 in legno all'ingrosso"},"content":{"rendered":"<p><strong>Tamponi per caff\u00e8 in legno all'ingrosso<\/strong><\/p>\n<p>Questo tamper per caff\u00e8 \u00e8 costituito da una solida base in acciaio inox, un manico in legno massiccio e una vite in metallo all'interno.<\/p>\n<p>Questo tipo di materiale si combina con la qualit\u00e0 premium dei tamponi per caff\u00e8.<\/p>\n<p>Se siete alla ricerca di rincalzatori di caff\u00e8 di buona qualit\u00e0, contattateci.<\/p>\n<p>Offriamo servizi personalizzati come LOGO, COLORE e IMBALLAGGIO.<\/p>","protected":false},"excerpt":{"rendered":"<p>Materiale: solida base da caff\u00e8 in acciaio inox, manico in legno massiccio.<\/p>\n<p>Dimensioni: 51 mm, 53 mm, 58 mm<\/p>\n<p>Opzioni di personalizzazione: colore, LOGO, confezione<\/p>\n<p>Base: piatta, filettata e personalizzabile<\/p>","protected":false},"featured_media":2529,"template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":{"0":"post-2528","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coffee-tamperscoffee-coffee-leveler","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product\/2528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product\/2528\/revisions"}],"predecessor-version":[{"id":2533,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product\/2528\/revisions\/2533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/media\/2529"}],"wp:attachment":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/media?parent=2528"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product_brand?post=2528"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product_cat?post=2528"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product_tag?post=2528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}