{"id":23,"count":20,"description":"I pressini e i livellatori per caff\u00e8 sono entrambi realizzati in solido acciaio inossidabile. Sul mercato sono disponibili alcune basi in plastica cromata. La loro qualit\u00e0 e il loro prezzo variano.","link":"https:\/\/pocencoffee.com\/it\/product-category\/pressini-per-caffe-livellatori-per-caffe\/","name":"Pressini per caff\u00e8 e livellatori per caff\u00e8","slug":"pressini-per-caffe-livellatori-per-caffe","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product_cat\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/pocencoffee.com\/it\/wp-json\/wp\/v2\/product?product_cat=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}